{"id":28250,"date":"2023-08-17T12:55:46","date_gmt":"2023-08-17T11:55:46","guid":{"rendered":"https:\/\/www.keepingchildrensafe.global\/los-estandares\/"},"modified":"2025-01-23T16:54:29","modified_gmt":"2025-01-23T16:54:29","slug":"los-estandares-internacionales-de-proteccion-infantil-organizacional","status":"publish","type":"page","link":"https:\/\/www.keepingchildrensafe.global\/es\/los-estandares-internacionales-de-proteccion-infantil-organizacional\/","title":{"rendered":"Los Est\u00e1ndares"},"content":{"rendered":"\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-cdc9e00c wp-block-columns-is-layout-flex\" style=\"padding-right:0px;padding-left:0px\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h1 class=\"wp-block-heading\" style=\"font-size:38px\">Los Est\u00e1ndares Internacionales <br>de Protecci\u00f3n Infantil Organizacional<\/h1>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"wp-block-paragraph\" style=\"font-size:16px\">Todos los ni\u00f1os, ni\u00f1as y adolescentes tienen derecho a estar a salvo del abuso, la explotaci\u00f3n y la negligencia.<\/p>\n<\/div>\n<\/div>\n\n\n\n<figure class=\"wp-block-image alignfull size-banner-image\"><img decoding=\"async\" data-src=\"https:\/\/www.keepingchildrensafe.global\/wp-content\/uploads\/2023\/10\/pexels-selman-15004705-1200x480.jpg\" alt=\"\" class=\"wp-image-1831 lazyload\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1200px; --smush-placeholder-aspect-ratio: 1200\/480;\" \/><\/figure>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-3dde82f3 wp-block-columns-is-layout-flex\" style=\"margin-top:0px;margin-bottom:0px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px\">\n<div class=\"wp-block-column has-ast-global-color-4-background-color has-background is-layout-flow wp-block-column-is-layout-flow\" style=\"padding-top:50px;padding-right:50px;padding-bottom:50px;padding-left:50px\">\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Los Est\u00e1ndares Internacionales de Protecci\u00f3n Infantil Organizacional de Keeping Children Safe ayudan a las organizaciones a cumplir las responsabilidades establecidas en la Convenci\u00f3n de las Naciones Unidas sobre los Derechos del Ni\u00f1o (CDN) para proteger a las infancias de los da\u00f1os causados por su personal, actividades, operaciones y socios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los Est\u00e1ndares describen los elementos clave que deben existir para proteger a las infancias y adolescencias, y enumeran los requisitos que deben cumplir las organizaciones para cumplirlas. Hay cuatro Est\u00e1ndares que abarcan: Pol\u00edtica, Personas, Procedimientos y Rendici\u00f3n de Cuentas. <\/p>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-buttons is-vertical is-layout-flex wp-container-core-buttons-is-layout-2c90304e wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-outline is-style-outline--1\"><a class=\"wp-block-button__link has-ast-global-color-5-color has-text-color wp-element-button\" href=\"https:\/\/www.ohchr.org\/es\/instruments-mechanisms\/instruments\/convention-rights-child\" target=\"_blank\" rel=\"noreferrer noopener\">La CDN<\/a><\/div>\n<\/div>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"padding-top:50px;padding-right:50px;padding-bottom:50px;padding-left:50px\">\n<div class=\"wp-block-essential-blocks-accordion acc-underline  root-eb-accordion-qe6aih8\"><div class=\"eb-parent-wrapper eb-parent-eb-accordion-qe6aih8 \"><div class=\"eb-accordion-container eb-accordion-qe6aih8\" data-accordion-type=\"accordion\" data-tab-icon=\"fas fa-angle-down\" data-expanded-icon=\"fas fa-angle-up\" data-transition-duration=\"500\"><div class=\"eb-accordion-inner\">\n<div class=\"wp-block-essential-blocks-accordion-item eb-accordion-item-0o4vkni eb-accordion-wrapper\" data-clickable=\"false\"><div class=\"eb-accordion-title-wrapper eb-accordion-title-wrapper-eb-accordion-qe6aih8\" tabindex=\"0\"><span class=\"eb-accordion-icon-wrapper eb-accordion-icon-wrapper-eb-accordion-qe6aih8\"><span class=\"fas fa-angle-down eb-accordion-icon\"><\/span><\/span><div class=\"eb-accordion-title-content-wrap title-content-eb-accordion-qe6aih8\"><h3 class=\"eb-accordion-title\">Est\u00e1ndares para todas las organizaciones<\/h3><\/div><\/div><div class=\"eb-accordion-content-wrapper eb-accordion-content-wrapper-eb-accordion-qe6aih8\"><div class=\"eb-accordion-content\">\n<p class=\"wp-block-paragraph\">Todos los ni\u00f1os, ni\u00f1as y adolescentes tienen derecho a estar seguros y todas las organizaciones tienen la responsabilidad de protegerles de cualquier da\u00f1o. <\/p>\n\n\n\n<div style=\"height:5px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Este da\u00f1o puede producirse por contacto directo o en l\u00ednea. Tambi\u00e9n puede ser el resultado de las actividades o programas de una organizaci\u00f3n. <\/p>\n\n\n\n<div style=\"height:5px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Los Est\u00e1ndares Internacionales de Protecci\u00f3n Infantil Organizacional se han aplicado en organizaciones de todos los sectores, en todas las regiones del mundo, para construir organizaciones m\u00e1s seguras para los ni\u00f1os, ni\u00f1as y adolescentes.<\/p>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-essential-blocks-accordion-item eb-accordion-item-d5zzvme eb-accordion-wrapper\" data-clickable=\"false\"><div class=\"eb-accordion-title-wrapper eb-accordion-title-wrapper-eb-accordion-qe6aih8\" tabindex=\"0\"><span class=\"eb-accordion-icon-wrapper eb-accordion-icon-wrapper-eb-accordion-qe6aih8\"><span class=\"fas fa-angle-down eb-accordion-icon\"><\/span><\/span><div class=\"eb-accordion-title-content-wrap title-content-eb-accordion-qe6aih8\"><h3 class=\"eb-accordion-title\">Principios rectores <\/h3><\/div><\/div><div class=\"eb-accordion-content-wrapper eb-accordion-content-wrapper-eb-accordion-qe6aih8\"><div class=\"eb-accordion-content\">\n<p class=\"wp-block-paragraph\">Los Est\u00e1ndares est\u00e1n basados en los siguientes principios rectores:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Todos los ni\u00f1os, ni\u00f1as y adolescentes tienen los mismos derechos a ser protegidos frente al da\u00f1o.<\/li>\n\n\n\n<li>Todas las personas tienen la responsabilidad de apoyar la protecci\u00f3n infantil organizacional.<\/li>\n\n\n\n<li>Las organizaciones tienen el deber de cuidar a los ni\u00f1os, ni\u00f1as y adolescentes con los que trabajan, con los que est\u00e1n en contacto o que se ven afectados por su trabajo y operaciones.<\/li>\n\n\n\n<li>Si las organizaciones trabajan con socios, tienen la responsabilidad de ayudarles a cumplir los requisitos m\u00ednimos de protecci\u00f3n infantil organizacional.<\/li>\n\n\n\n<li>Todas las acciones relativas a la protecci\u00f3n infantil organizacional deben adoptarse con en el inter\u00e9s superior del ni\u00f1o, ni\u00f1a o adolescente en mente, que es primordial.<\/li>\n<\/ul>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-essential-blocks-accordion-item eb-accordion-item-kbos357 eb-accordion-wrapper\" data-clickable=\"false\"><div class=\"eb-accordion-title-wrapper eb-accordion-title-wrapper-eb-accordion-qe6aih8\" tabindex=\"0\"><span class=\"eb-accordion-icon-wrapper eb-accordion-icon-wrapper-eb-accordion-qe6aih8\"><span class=\"fas fa-angle-down eb-accordion-icon\"><\/span><\/span><div class=\"eb-accordion-title-content-wrap title-content-eb-accordion-qe6aih8\"><h3 class=\"eb-accordion-title\">Aplicando los Est\u00e1ndares<\/h3><\/div><\/div><div class=\"eb-accordion-content-wrapper eb-accordion-content-wrapper-eb-accordion-qe6aih8\"><div class=\"eb-accordion-content\">\n<p class=\"wp-block-paragraph\">\u00danase a cientos de miles de defensores de la protecci\u00f3n infantil organizacional en todo el mundo descargando nuestras herramientas y recursos gratuitos para ayudarle a aplicar los Est\u00e1ndares en su organizaci\u00f3n. <\/p>\n\n\n\n<div style=\"height:5px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">O p\u00f3ngase en contacto con nuestro Equipo de Est\u00e1ndares y Aprendizaje para obtener asesoramiento y apoyo.<\/p>\n\n\n\n<div style=\"height:5px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"arrow-list wp-block-paragraph\"><a href=\"mailto:info@keepingchildrensafe.global\" target=\"_blank\" rel=\"noreferrer noopener\">P\u00f3ngase en contacto con nosotros<\/a><\/p>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div><\/div><\/div>\n<\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><style>\/*! elementor - v3.15.0 - 20-08-2023 *\/&amp;amp;amp;lt;br \/> .elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}\/*! elementor - v3.15.0 - 20-08-2023 *\/&amp;amp;amp;amp;amp;lt;br \/> .elementor-accordion{text-align:left}.elementor-accordion .elementor-accordion-item{border:1px solid #d5d8dc}.elementor-accordion .elementor-accordion-item+.elementor-accordion-item{border-top:none}.elementor-accordion .elementor-tab-title{margin:0;padding:15px 20px;font-weight:700;line-height:1;cursor:pointer;outline:none}.elementor-accordion .elementor-tab-title .elementor-accordion-icon{display:inline-block;width:1.5em}.elementor-accordion .elementor-tab-title .elementor-accordion-icon svg{width:1em;height:1em}.elementor-accordion .elementor-tab-title .elementor-accordion-icon.elementor-accordion-icon-right{float:right;text-align:right}.elementor-accordion .elementor-tab-title .elementor-accordion-icon.elementor-accordion-icon-left{float:left;text-align:left}.elementor-accordion .elementor-tab-title .elementor-accordion-icon .elementor-accordion-icon-closed{display:block}.elementor-accordion .elementor-tab-title .elementor-accordion-icon .elementor-accordion-icon-opened,.elementor-accordion .elementor-tab-title.elementor-active .elementor-accordion-icon-closed{display:none}.elementor-accordion .elementor-tab-title.elementor-active .elementor-accordion-icon-opened{display:block}.elementor-accordion .elementor-tab-content{display:none;padding:15px 20px;border-top:1px solid #d5d8dc}@media (max-width:767px){.elementor-accordion .elementor-tab-title{padding:12px 15px}.elementor-accordion .elementor-tab-title .elementor-accordion-icon{width:1.2em}.elementor-accordion .elementor-tab-content{padding:7px 15px}}.e-con-inner>.elementor-widget-accordion,.e-con>.elementor-widget-accordion{width:var(--container-widget-width);--flex-grow:var(--container-widget-flex-grow)}<\/style><\/p>\n\n\n\n<div style=\"height:90px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-essential-blocks-accordion numbered-tabs  root-eb-accordion-v49g2tn\"><div class=\"eb-parent-wrapper eb-parent-eb-accordion-v49g2tn \"><div class=\"eb-accordion-container eb-accordion-v49g2tn\" data-accordion-type=\"accordion\" data-tab-icon=\"fas fa-angle-down\" data-expanded-icon=\"fas fa-angle-up\" data-transition-duration=\"500\"><div class=\"eb-accordion-inner\">\n<div class=\"wp-block-essential-blocks-accordion-item eb-accordion-item-n3zn0nh eb-accordion-wrapper\" data-clickable=\"false\"><div class=\"eb-accordion-title-wrapper eb-accordion-title-wrapper-eb-accordion-v49g2tn\" tabindex=\"0\"><span class=\"eb-accordion-icon-wrapper eb-accordion-icon-wrapper-eb-accordion-v49g2tn\"><span class=\"fas fa-angle-down eb-accordion-icon\"><\/span><\/span><div class=\"eb-accordion-title-content-wrap title-content-eb-accordion-v49g2tn\"><h3 class=\"eb-accordion-title\">Pol\u00edtica <\/h3><\/div><\/div><div class=\"eb-accordion-content-wrapper eb-accordion-content-wrapper-eb-accordion-v49g2tn\"><div class=\"eb-accordion-content\">\n<p class=\"wp-block-paragraph\">La organizaci\u00f3n desarrolla una pol\u00edtica que describe c\u00f3mo est\u00e1 comprometida a prevenir y responder de forma apropiada a cualquier da\u00f1o infligido sobre ni\u00f1os, ni\u00f1as o adolescentes.<\/p>\n\n\n\n<div style=\"height:5px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">La pol\u00edtica refleja el derecho de las infancias y adolescencias a ser protegidas, establecido en la Convenci\u00f3n sobre los Derechos del Ni\u00f1o de Naciones Unidas (CDN).<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>La pol\u00edtica es aprobada por el \u00f3rgano de direcci\u00f3n de la organizaci\u00f3n y se aplica a todo su personal y asociados.<\/li>\n\n\n\n<li>La pol\u00edtica se da a conocer de forma adecuada, se promueve y se distribuye ampliamente, tambi\u00e9n entre las infancias y sus cuidadores.<\/li>\n<\/ul>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-essential-blocks-accordion-item eb-accordion-item-y0ccg67 eb-accordion-wrapper\" data-clickable=\"false\"><div class=\"eb-accordion-title-wrapper eb-accordion-title-wrapper-eb-accordion-v49g2tn\" tabindex=\"0\"><span class=\"eb-accordion-icon-wrapper eb-accordion-icon-wrapper-eb-accordion-v49g2tn\"><span class=\"fas fa-angle-down eb-accordion-icon\"><\/span><\/span><div class=\"eb-accordion-title-content-wrap title-content-eb-accordion-v49g2tn\"><h3 class=\"eb-accordion-title\">Personas<\/h3><\/div><\/div><div class=\"eb-accordion-content-wrapper eb-accordion-content-wrapper-eb-accordion-v49g2tn\"><div class=\"eb-accordion-content\">\n<p class=\"wp-block-paragraph\">La organizaci\u00f3n establece responsabilidades y expectativas claras a su personal y asociados y les ayuda a comprenderlas y actuar en consonancia con ellas. En diferentes niveles, incluido a nivel de direcci\u00f3n, miembros del personal clave son designados como \u00abpuntos focales\u00bb de protecci\u00f3n infantil organizacional, con funciones y responsabilidades claramente definidas.<\/p>\n\n\n\n<div style=\"height:5px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Los procesos de contrataci\u00f3n cuentan con s\u00f3lidas medidas de protecci\u00f3n infantil organizacional.<\/li>\n\n\n\n<li>Existen lineamientos por escrito sobre el comportamiento adecuado e inadecuado de adultos hacia los ni\u00f1os, ni\u00f1as y adolescentes y entre pares.<\/li>\n\n\n\n<li>Existen lineamientos para implicar a los socios, las comunidades y los ni\u00f1os, ni\u00f1as y adolescentes en la protecci\u00f3n infantil organizacional.<\/li>\n<\/ul>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-essential-blocks-accordion-item eb-accordion-item-gd2ipyv eb-accordion-wrapper\" data-clickable=\"false\"><div class=\"eb-accordion-title-wrapper eb-accordion-title-wrapper-eb-accordion-v49g2tn\" tabindex=\"0\"><span class=\"eb-accordion-icon-wrapper eb-accordion-icon-wrapper-eb-accordion-v49g2tn\"><span class=\"fas fa-angle-down eb-accordion-icon\"><\/span><\/span><div class=\"eb-accordion-title-content-wrap title-content-eb-accordion-v49g2tn\"><h3 class=\"eb-accordion-title\">Procedimientos<\/h3><\/div><\/div><div class=\"eb-accordion-content-wrapper eb-accordion-content-wrapper-eb-accordion-v49g2tn\"><div class=\"eb-accordion-content\">\n<p class=\"wp-block-paragraph\">La organizaci\u00f3n crea un entorno seguro para ni\u00f1os, ni\u00f1as y adolescentes mediante la implementaci\u00f3n de procedimientos de protecci\u00f3n infantil organizacional que se aplican en toda la organizaci\u00f3n.<\/p>\n\n\n\n<div style=\"height:5px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Las organizaciones llevan a cabo ejercicios de mapeo que proporcionan informaci\u00f3n sobre las disposiciones legales, de bienestar social y de protecci\u00f3n de infantil locales.<\/li>\n\n\n\n<li>Las evaluaciones de riesgos de protecci\u00f3n infantil organizacional y las estrategias de mitigaci\u00f3n se incorporan a los procesos de evaluaci\u00f3n de riesgos existentes en todos los niveles.<\/li>\n\n\n\n<li>Las medidas de protecci\u00f3n infantil organizacional se integran en los procesos y sistemas existentes (como en la planificaci\u00f3n estrat\u00e9gica, la elaboraci\u00f3n de presupuestos, contrataciones, los programas, la gesti\u00f3n de ciclos, la gesti\u00f3n del rendimiento, las nuevas adquisiciones, los acuerdos con socios y sistemas de gesti\u00f3n, etc.).<\/li>\n\n\n\n<li>Se desarrolla un proceso de notificaci\u00f3n y respuesta a incidentes y denuncias adecuado a nivel local.<\/li>\n<\/ul>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-essential-blocks-accordion-item eb-accordion-item-wguesnn eb-accordion-wrapper\" data-clickable=\"false\"><div class=\"eb-accordion-title-wrapper eb-accordion-title-wrapper-eb-accordion-v49g2tn\" tabindex=\"0\"><span class=\"eb-accordion-icon-wrapper eb-accordion-icon-wrapper-eb-accordion-v49g2tn\"><span class=\"fas fa-angle-down eb-accordion-icon\"><\/span><\/span><div class=\"eb-accordion-title-content-wrap title-content-eb-accordion-v49g2tn\"><h3 class=\"eb-accordion-title\">Rendici\u00f3n de cuentas y responsabilidad<\/h3><\/div><\/div><div class=\"eb-accordion-content-wrapper eb-accordion-content-wrapper-eb-accordion-v49g2tn\"><div class=\"eb-accordion-content\">\n<p class=\"wp-block-paragraph\">La organizaci\u00f3n supervisa y revisa sus medidas de protecci\u00f3n infantil organizacional.<\/p>\n\n\n\n<div style=\"height:5px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<ul class=\"wp-block-list\">\n<li>La aplicaci\u00f3n de las pol\u00edticas y procedimientos de protecci\u00f3n infantil organizacional se supervisa peri\u00f3dicamente.<\/li>\n\n\n\n<li>Los avances, el rendimiento y las lecciones aprendidas se comunican a las principales partes interesadas (como foros de gesti\u00f3n y organismos externos o independientes, si corresponde) y se incluyen en los informes anuales de las organizaciones.<\/li>\n\n\n\n<li>Las ense\u00f1anzas extra\u00eddas de la experiencia pr\u00e1ctica sirven de base para revisar las pol\u00edticas y modificar las medidas de protecci\u00f3n infantil organizacional.<\/li>\n\n\n\n<li>Las pol\u00edticas y pr\u00e1cticas se revisan con regularidad y son evaluadas formalmente por un evaluador\/auditor externo cada tres a\u00f1os.<\/li>\n<\/ul>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div><\/div><\/div>\n\n\n\n<div style=\"height:90px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:26px\">Descargue los Est\u00e1ndares y nuestros recursos gratuitos sobre protecci\u00f3n infantil organizacional. <\/p>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-columns promo-trio promo-trio-3colours is-layout-flex wp-container-core-columns-is-layout-4186c0c2 wp-block-columns-is-layout-flex\" style=\"padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px\">\n<div class=\"wp-block-column has-ast-global-color-4-background-color has-background is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"arrow-right wp-block-paragraph\" style=\"font-size:26px\"><a href=\"https:\/\/www.keepingchildrensafe.global\/resources\/international-child-safeguarding-standards\/\" target=\"_blank\" rel=\"noreferrer noopener\">Est\u00e1ndares Internacionales de Protecci\u00f3n Infantil Organizacional<\/a><\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-ast-global-color-5-color has-ast-global-color-0-background-color has-text-color has-background wp-element-button\" href=\"https:\/\/www.keepingchildrensafe.global\/wp-content\/uploads\/2023\/09\/KCS_ChildSafeguardingStandards_ES_2020_FINAL22.pdf\">Descargar en Espa\u00f1ol<\/a><\/div>\n\n\n\n<div class=\"wp-block-button is-style-outline is-style-outline--2\"><a class=\"wp-block-button__link has-ast-global-color-5-color has-text-color wp-element-button\" href=\"https:\/\/www.keepingchildrensafe.global\/wp-content\/uploads\/2024\/08\/KCS-ICS-Standards-EN-2024.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Ver otros idiomas<\/a><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column has-ast-global-color-5-color has-ast-global-color-4-background-color has-text-color has-background is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"arrow-right wp-block-paragraph\" style=\"font-size:26px\"><a href=\"https:\/\/www.keepingchildrensafe.global\/resources\/international-child-safeguarding-standards\/\" target=\"_blank\" rel=\"noreferrer noopener\">Desarrollando pol\u00edticas y procedimientos de protecci\u00f3n infantil organizacional<\/a><\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-ast-global-color-5-color has-ast-global-color-0-background-color has-text-color has-background wp-element-button\" href=\"https:\/\/www.keepingchildrensafe.global\/wp-content\/uploads\/2023\/09\/Developing-CS-Spanish.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Descargar en Espa\u00f1ol<\/a><\/div>\n\n\n\n<div class=\"wp-block-button is-style-outline is-style-outline--3\"><a class=\"wp-block-button__link has-ast-global-color-5-color has-text-color wp-element-button\" href=\"https:\/\/www.keepingchildrensafe.global\/wp-content\/uploads\/2023\/09\/KCS-Developing-Child-Safeguarding-200218.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Ver otros idiomas<\/a><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column has-ast-global-color-5-color has-ast-global-color-0-background-color has-text-color has-background is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"arrow-right arrow-right-white has-ast-global-color-5-color has-text-color wp-block-paragraph\" style=\"font-size:26px\"><a href=\"https:\/\/www.keepingchildrensafe.global\/es\/autoevaluacion-de-proteccion-infantil-organizacional\/\" target=\"_blank\" rel=\"noreferrer noopener\">Herramienta de autoevaluaci\u00f3n gratuita en l\u00ednea<\/a><\/p>\n\n\n\n<p class=\"has-ast-global-color-5-color has-text-color wp-block-paragraph\">Descubra qu\u00e9 tan cerca o lejos est\u00e1 su organizaci\u00f3n de cumplir con los Est\u00e1ndares.<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-essential-blocks-popup nlp  root-eb-popup-h704f\"><div class=\"eb-parent-wrapper\"><div id=\"eb-popup-h704f\" class=\"eb-popup-container eb-popup-h704f\" data-block-id=\"eb-popup-h704f\" data-popup-type=\"page_load\" data-popup-delay=\"5\" data-close-btn=\"true\" data-esc-btn=\"true\" data-click-exit=\"true\" data-auto-exit=\"false\" data-auto-exit-time=\"3\" data-use-cookie=\"true\" data-cookie-expire-time=\"90\"><div class=\"eb-popup-btn-wrapper eb-parent-eb-popup-h704f \"><\/div><div class=\"eb-popup-overlay\"><\/div><div class=\"modal-main-wrap\"><div class=\"eb-modal-container eb_popup_middle_center\"><div class=\"eb-popup-content\"><div class=\"eb-popup-close-icon\"><span class=\"dashicons dashicons-no-alt\"><\/span><\/div>\n<div class=\"wp-block-columns newsletter-popup is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;flex-basis:36.1%\">\n<figure class=\"wp-block-image size-full newsletter-popup-image\"><img decoding=\"async\" data-src=\"https:\/\/www.keepingchildrensafe.global\/wp-content\/uploads\/2024\/06\/pexels-kindel-media-7106007-scaled.jpg\" alt=\"\" class=\"wp-image-27771 lazyload\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1126px; --smush-placeholder-aspect-ratio: 1126\/2000;\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<figure class=\"wp-block-image size-full is-resized\"><img decoding=\"async\" width=\"500\" height=\"53\" data-src=\"https:\/\/www.keepingchildrensafe.global\/wp-content\/uploads\/2024\/06\/kcs-header-logo-1.png\" alt=\"\" class=\"wp-image-26438 lazyload\" style=\"--smush-placeholder-width: 500px; --smush-placeholder-aspect-ratio: 500\/53;width:250px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><\/figure>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading popup-headline\">Suscr\u00edbase a nuestro bolet\u00edn electr\u00f3nico<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Reciba directamente en su bandeja de entrada las \u00faltimas noticias, herramientas y recursos sobre protecci\u00f3n infantil organizacional. <\/p>\n\n\n\n<div class=\"wp-block-columns en-only is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px\">\n<div class=\"newsletter-popup-form\">  \n<div id=\"mc_embed_signup\">\n    <form action=\"https:\/\/global.us18.list-manage.com\/subscribe\/post?u=c53792304124d6235236f91e5&#038;id=ac4a7fd3b8&#038;v_id=5734&#038;f_id=004229e7f0\" method=\"post\" id=\"mc-embedded-subscribe-form\" name=\"mc-embedded-subscribe-form\" class=\"validate\" target=\"_self\" novalidate=\"\">\n        <div id=\"mc_embed_signup_scroll\">\n            <div class=\"mc-field-group\"><label for=\"mce-EMAIL\" style=\"position: absolute; left: -5000px;\">Su correo electr\u00f3nico<\/label><input type=\"email\" name=\"EMAIL\" class=\"required email\" id=\"mce-EMAIL\" required=\"\" value=\"\" placeholder=\"Su correo electr\u00f3nico\"\/><\/div>\n        <div id=\"mce-responses\" class=\"clear\">\n            <div class=\"response\" id=\"mce-error-response\" style=\"display: none;\"><\/div>\n            <div class=\"response\" id=\"mce-success-response\" style=\"display: none;\"><\/div>\n        <\/div><div aria-hidden=\"true\" style=\"position: absolute; left: -5000px;\"><input type=\"text\" name=\"b_c53792304124d6235236f91e5_ac4a7fd3b8\" tabindex=\"-1\" value=\"\"\/><\/div>\n\t\t<div class=\"clear\"><input type=\"submit\" name=\"subscribe\" id=\"mc-embedded-subscribe\" class=\"button button-purple\" value=\"Suscr\u00edbase\"\/><\/div>\n    <\/div>\n<\/form>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns es-only is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px\">\n<div class=\"newsletter-popup-form\"> \n  <div id=\"mc_embed_signup\">\n    <form action=\"https:\/\/global.us18.list-manage.com\/subscribe\/post?u=c53792304124d6235236f91e5&#038;id=0aa651e421&#038;v_id=5701&#038;f_id=002991e6f0\" method=\"post\" id=\"mc-embedded-subscribe-form\" name=\"mc-embedded-subscribe-form\" class=\"validate\" target=\"_self\" novalidate=\"\">\n        <div id=\"mc_embed_signup_scroll\">\n           <div class=\"mc-field-group\"><label for=\"mce-EMAIL\" style=\"position: absolute; left: -5000px;\">Su correo electr\u00f3nico<\/label><input type=\"email\" name=\"EMAIL\" class=\"required email\" id=\"mce-EMAIL\" required=\"\" value=\"\" placeholder=\"Su correo electr\u00f3nico\"\/><\/div>\n        <div id=\"mce-responses\" class=\"clear\">\n            <div class=\"response\" id=\"mce-error-response\" style=\"display: none;\"><\/div>\n            <div class=\"response\" id=\"mce-success-response\" style=\"display: none;\"><\/div>\n        <\/div><div aria-hidden=\"true\" style=\"position: absolute; left: -5000px;\"><input type=\"text\" name=\"b_c53792304124d6235236f91e5_0aa651e421\" tabindex=\"-1\" value=\"\"\/><\/div>\n\t\t<div class=\"clear\"><input type=\"submit\" name=\"subscribe\" id=\"mc-embedded-subscribe\" class=\"button button-purple\" value=\"Suscr\u00edbase\"\/><\/div>\n    <\/div>\n<\/form>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Los Est\u00e1ndares Internacionales de Protecci\u00f3n Infantil Organizacional Todos los ni\u00f1os, ni\u00f1as y adolescentes tienen derecho a estar a salvo del abuso, la explotaci\u00f3n y la negligencia. Los Est\u00e1ndares Internacionales de Protecci\u00f3n Infantil Organizacional de Keeping Children Safe ayudan a las organizaciones a cumplir las responsabilidades establecidas en la Convenci\u00f3n de las Naciones Unidas sobre los [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_eb_attr":"","site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-28250","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Los Est\u00e1ndares - Keeping Children Safe<\/title>\n<meta name=\"description\" content=\"Todos los ni\u00f1os, ni\u00f1as y adolescentes tienen derecho a estar a salvo del abuso, la explotaci\u00f3n y la negligencia. Conozca m\u00e1s sobre los Est\u00e1ndares Internacionales de Protecci\u00f3n Infantil Organizacional.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.keepingchildrensafe.global\/es\/los-estandares-internacionales-de-proteccion-infantil-organizacional\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Los Est\u00e1ndares - Keeping Children Safe\" \/>\n<meta property=\"og:description\" content=\"Todos los ni\u00f1os, ni\u00f1as y adolescentes tienen derecho a estar a salvo del abuso, la explotaci\u00f3n y la negligencia. Conozca m\u00e1s sobre los Est\u00e1ndares Internacionales de Protecci\u00f3n Infantil Organizacional.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.keepingchildrensafe.global\/es\/los-estandares-internacionales-de-proteccion-infantil-organizacional\/\" \/>\n<meta property=\"og:site_name\" content=\"Keeping Children Safe\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/KCSkeepingchildrensafe\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-23T16:54:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.keepingchildrensafe.global\/wp-content\/uploads\/2023\/10\/pexels-selman-15004705-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2800\" \/>\n\t<meta property=\"og:image:height\" content=\"1575\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@keepchildsafe\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.keepingchildrensafe.global\\\/es\\\/los-estandares-internacionales-de-proteccion-infantil-organizacional\\\/\",\"url\":\"https:\\\/\\\/www.keepingchildrensafe.global\\\/es\\\/los-estandares-internacionales-de-proteccion-infantil-organizacional\\\/\",\"name\":\"Los Est\u00e1ndares - Keeping Children Safe\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.keepingchildrensafe.global\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.keepingchildrensafe.global\\\/es\\\/los-estandares-internacionales-de-proteccion-infantil-organizacional\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.keepingchildrensafe.global\\\/es\\\/los-estandares-internacionales-de-proteccion-infantil-organizacional\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.keepingchildrensafe.global\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/pexels-selman-15004705-1200x480.jpg\",\"datePublished\":\"2023-08-17T11:55:46+00:00\",\"dateModified\":\"2025-01-23T16:54:29+00:00\",\"description\":\"Todos los ni\u00f1os, ni\u00f1as y adolescentes tienen derecho a estar a salvo del abuso, la explotaci\u00f3n y la negligencia. Conozca m\u00e1s sobre los Est\u00e1ndares Internacionales de Protecci\u00f3n Infantil Organizacional.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.keepingchildrensafe.global\\\/es\\\/los-estandares-internacionales-de-proteccion-infantil-organizacional\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.keepingchildrensafe.global\\\/es\\\/los-estandares-internacionales-de-proteccion-infantil-organizacional\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.keepingchildrensafe.global\\\/es\\\/los-estandares-internacionales-de-proteccion-infantil-organizacional\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.keepingchildrensafe.global\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/pexels-selman-15004705-1200x480.jpg\",\"contentUrl\":\"https:\\\/\\\/www.keepingchildrensafe.global\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/pexels-selman-15004705-1200x480.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.keepingchildrensafe.global\\\/es\\\/los-estandares-internacionales-de-proteccion-infantil-organizacional\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.keepingchildrensafe.global\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Los Est\u00e1ndares\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.keepingchildrensafe.global\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.keepingchildrensafe.global\\\/es\\\/\",\"name\":\"Keeping Children Safe\",\"description\":\"Setting tough International Child Safeguarding Standards\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.keepingchildrensafe.global\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.keepingchildrensafe.global\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.keepingchildrensafe.global\\\/es\\\/#organization\",\"name\":\"Keeping Children Safe\",\"url\":\"https:\\\/\\\/www.keepingchildrensafe.global\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.keepingchildrensafe.global\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/kcs.webscapegardener.site\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/kcs-header-logo.png\",\"contentUrl\":\"https:\\\/\\\/kcs.webscapegardener.site\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/kcs-header-logo.png\",\"width\":204,\"height\":21,\"caption\":\"Keeping Children Safe\"},\"image\":{\"@id\":\"https:\\\/\\\/www.keepingchildrensafe.global\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/KCSkeepingchildrensafe\",\"https:\\\/\\\/x.com\\\/keepchildsafe\",\"https:\\\/\\\/www.instagram.com\\\/keepingchildrensafe\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/keeping-children-safe-coalition\\\/\",\"https:\\\/\\\/vimeo.com\\\/keepingchildrensafe\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Los Est\u00e1ndares - Keeping Children Safe","description":"Todos los ni\u00f1os, ni\u00f1as y adolescentes tienen derecho a estar a salvo del abuso, la explotaci\u00f3n y la negligencia. Conozca m\u00e1s sobre los Est\u00e1ndares Internacionales de Protecci\u00f3n Infantil Organizacional.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.keepingchildrensafe.global\/es\/los-estandares-internacionales-de-proteccion-infantil-organizacional\/","og_locale":"es_ES","og_type":"article","og_title":"Los Est\u00e1ndares - Keeping Children Safe","og_description":"Todos los ni\u00f1os, ni\u00f1as y adolescentes tienen derecho a estar a salvo del abuso, la explotaci\u00f3n y la negligencia. Conozca m\u00e1s sobre los Est\u00e1ndares Internacionales de Protecci\u00f3n Infantil Organizacional.","og_url":"https:\/\/www.keepingchildrensafe.global\/es\/los-estandares-internacionales-de-proteccion-infantil-organizacional\/","og_site_name":"Keeping Children Safe","article_publisher":"https:\/\/www.facebook.com\/KCSkeepingchildrensafe","article_modified_time":"2025-01-23T16:54:29+00:00","og_image":[{"width":2800,"height":1575,"url":"https:\/\/www.keepingchildrensafe.global\/wp-content\/uploads\/2023\/10\/pexels-selman-15004705-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@keepchildsafe","twitter_misc":{"Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.keepingchildrensafe.global\/es\/los-estandares-internacionales-de-proteccion-infantil-organizacional\/","url":"https:\/\/www.keepingchildrensafe.global\/es\/los-estandares-internacionales-de-proteccion-infantil-organizacional\/","name":"Los Est\u00e1ndares - Keeping Children Safe","isPartOf":{"@id":"https:\/\/www.keepingchildrensafe.global\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.keepingchildrensafe.global\/es\/los-estandares-internacionales-de-proteccion-infantil-organizacional\/#primaryimage"},"image":{"@id":"https:\/\/www.keepingchildrensafe.global\/es\/los-estandares-internacionales-de-proteccion-infantil-organizacional\/#primaryimage"},"thumbnailUrl":"https:\/\/www.keepingchildrensafe.global\/wp-content\/uploads\/2023\/10\/pexels-selman-15004705-1200x480.jpg","datePublished":"2023-08-17T11:55:46+00:00","dateModified":"2025-01-23T16:54:29+00:00","description":"Todos los ni\u00f1os, ni\u00f1as y adolescentes tienen derecho a estar a salvo del abuso, la explotaci\u00f3n y la negligencia. Conozca m\u00e1s sobre los Est\u00e1ndares Internacionales de Protecci\u00f3n Infantil Organizacional.","breadcrumb":{"@id":"https:\/\/www.keepingchildrensafe.global\/es\/los-estandares-internacionales-de-proteccion-infantil-organizacional\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.keepingchildrensafe.global\/es\/los-estandares-internacionales-de-proteccion-infantil-organizacional\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.keepingchildrensafe.global\/es\/los-estandares-internacionales-de-proteccion-infantil-organizacional\/#primaryimage","url":"https:\/\/www.keepingchildrensafe.global\/wp-content\/uploads\/2023\/10\/pexels-selman-15004705-1200x480.jpg","contentUrl":"https:\/\/www.keepingchildrensafe.global\/wp-content\/uploads\/2023\/10\/pexels-selman-15004705-1200x480.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.keepingchildrensafe.global\/es\/los-estandares-internacionales-de-proteccion-infantil-organizacional\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.keepingchildrensafe.global\/es\/"},{"@type":"ListItem","position":2,"name":"Los Est\u00e1ndares"}]},{"@type":"WebSite","@id":"https:\/\/www.keepingchildrensafe.global\/es\/#website","url":"https:\/\/www.keepingchildrensafe.global\/es\/","name":"Keeping Children Safe","description":"Setting tough International Child Safeguarding Standards","publisher":{"@id":"https:\/\/www.keepingchildrensafe.global\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.keepingchildrensafe.global\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.keepingchildrensafe.global\/es\/#organization","name":"Keeping Children Safe","url":"https:\/\/www.keepingchildrensafe.global\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.keepingchildrensafe.global\/es\/#\/schema\/logo\/image\/","url":"https:\/\/kcs.webscapegardener.site\/wp-content\/uploads\/2023\/10\/kcs-header-logo.png","contentUrl":"https:\/\/kcs.webscapegardener.site\/wp-content\/uploads\/2023\/10\/kcs-header-logo.png","width":204,"height":21,"caption":"Keeping Children Safe"},"image":{"@id":"https:\/\/www.keepingchildrensafe.global\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/KCSkeepingchildrensafe","https:\/\/x.com\/keepchildsafe","https:\/\/www.instagram.com\/keepingchildrensafe\/","https:\/\/www.linkedin.com\/company\/keeping-children-safe-coalition\/","https:\/\/vimeo.com\/keepingchildrensafe"]}]}},"_links":{"self":[{"href":"https:\/\/www.keepingchildrensafe.global\/es\/wp-json\/wp\/v2\/pages\/28250","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.keepingchildrensafe.global\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.keepingchildrensafe.global\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.keepingchildrensafe.global\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.keepingchildrensafe.global\/es\/wp-json\/wp\/v2\/comments?post=28250"}],"version-history":[{"count":32,"href":"https:\/\/www.keepingchildrensafe.global\/es\/wp-json\/wp\/v2\/pages\/28250\/revisions"}],"predecessor-version":[{"id":30344,"href":"https:\/\/www.keepingchildrensafe.global\/es\/wp-json\/wp\/v2\/pages\/28250\/revisions\/30344"}],"wp:attachment":[{"href":"https:\/\/www.keepingchildrensafe.global\/es\/wp-json\/wp\/v2\/media?parent=28250"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}