{"id":13544,"date":"2021-08-17T00:00:00","date_gmt":"2021-08-16T23:00:00","guid":{"rendered":"https:\/\/www.keepingchildrensafe.global\/blog\/2021\/08\/17\/capacitacion-del-personal-de-mantenimiento-de-la-paz-de-las-naciones-unidas-en-proteccion-infantil-organizacional\/"},"modified":"2023-10-19T16:50:48","modified_gmt":"2023-10-19T15:50:48","slug":"capacitacion-del-personal-de-mantenimiento-de-la-paz-de-las-naciones-unidas-en-proteccion-infantil-organizacional","status":"publish","type":"post","link":"https:\/\/www.keepingchildrensafe.global\/es\/blog\/2021\/08\/17\/capacitacion-del-personal-de-mantenimiento-de-la-paz-de-las-naciones-unidas-en-proteccion-infantil-organizacional\/","title":{"rendered":"Capacitaci\u00f3n del personal de mantenimiento de la paz de las Naciones Unidas en Protecci\u00f3n Infantil Organizacional"},"content":{"rendered":"<p><b>El <\/b><a href=\"https:\/\/en.wikipedia.org\/wiki\/Ministry_of_National_Defense_(Uruguay)\"><b>Ministerio de Defensa Nacional<\/b><\/a> <b>de Uruguay ha lanzado una innovadora gu\u00eda de capacitaci\u00f3n sobre la protecci\u00f3n organizacional de la infancia contra la explotaci\u00f3n y el abuso en el contexto de las misiones de mantenimiento de la paz de las Naciones Unidas.<\/b> <\/p>\n<p>La gu\u00eda, la primera a nivel mundial, fue desarrollada en colaboraci\u00f3n con Keeping Children Safe, UNICEF Uruguay, la Embajada brit\u00e1nica en Montevideo y el Ministerio de Defensa brit\u00e1nico. Se basa en investigaci\u00f3n de la Universidad de Reading y Keeping Children Safe como parte de una colaboraci\u00f3n continua para establecer un Centro de Excelencia en Protecci\u00f3n Infantil Organizacional en el mantenimiento de la paz en Uruguay.<\/p>\n<p>En 2020, Uruguay se convirti\u00f3 en el primer pa\u00eds del mundo en formalizar su compromiso con la Protecci\u00f3n Infantil Organizacional con la firma de una pol\u00edtica para el personal desplegado en las <a href=\"https:\/\/www.keepingchildrensafe.global\/blog\/2020\/02\/27\/uruguays-military-leads-on-child-safeguarding\/\">misiones de mantenimiento de la paz de la ONU.<\/a> Vea a Alex Dressler, Jefe de Capacitaci\u00f3n en KCS, ofrecer una<a href=\"https:\/\/www.teledoce.com\/telemundo\/nacionales\/los-soldados-uruguayos-que-participan-en-misiones-de-paz-seran-capacitados-para-la-proteccion-de-los-ninos-de-los-paises-donde-son-desplegados\/\"> entrevista televisiva<\/a> (0:36 secs) en el lanzamiento de la pol\u00edtica en febrero de 2020.<\/p>\n<p>Consulte la p\u00e1gina de lanzamiento de <a href=\"https:\/\/www.gub.uy\/ministerio-defensa-nacional\/comunicacion\/noticias\/uruguay-presento-guia-capacitacion-para-instructores-proteccion-infantil\">la pol\u00edtica<\/a> del Ministerio para obtener m\u00e1s fotos.<\/p>\n<p>&nbsp;<\/p>\n<p><i>\u00abAl poner la Protecci\u00f3n Infantil Organizacional en el centro de la planificaci\u00f3n militar, Uruguay est\u00e1 liderando los esfuerzos internacionales para prevenir las violaciones de derechos humanos en el contexto de las misiones de mantenimiento de la paz de la ONU. Esperamos que otros pa\u00edses que aportan contingentes sigan este ejemplo y hagan todo lo posible para proteger a ni\u00f1os y ni\u00f1as de la explotaci\u00f3n y el abuso.\u00bb<\/i><\/p>\n<p>Sarah Blakemore<br \/>\nDirectora Ejecutivo de KCS<\/p>\n<p>&nbsp;<\/p>\n<p><i>\u00abUruguay es el primer pa\u00eds del mundo en contar con una pol\u00edtica Protecci\u00f3n Infantil Organizacional para las misiones de mantenimiento de la paz. Presentar esta gu\u00eda, este protocolo, y ser el primer pa\u00eds del mundo que lo hace, habla claramente de un compromiso. Las Fuerzas Armadas del Uruguay est\u00e1n comprometidas con los derechos humanos y con la paz. Es un compromiso que se asume a nivel nacional pero obviamente por las responsabilidades que tenemos y por nuestra participaci\u00f3n en el concierto de las Naciones Unidas, tambi\u00e9n como un compromiso internacional.<\/i><\/p>\n<p><i>Estamos dispuestos a colaborar con otros contingentes y con otros pa\u00edses para que esta gu\u00eda de acci\u00f3n sea la norma a seguir por todos aquellos que pretendemos colaborar con la protecci\u00f3n de los derechos de los m\u00e1s necesitados, de aquellos m\u00e1s vulnerables en los lugares que m\u00e1s necesidad hay en el mundo<\/i><\/p>\n<p><i>La presentaci\u00f3n del protocolo de hoy es el fin de una etapa y el comienzo de otra. Es el comienzo de una etapa de instrucci\u00f3n, de formaci\u00f3n, de divulgaci\u00f3n de gu\u00edas que hacen proteger a los ni\u00f1os, a las ni\u00f1as y a los adolescentes contra toda vulneraci\u00f3n de los derechos humanos y contra todo tipo de abuso y al mismo tiempo, irradiar estas pr\u00e1cticas protectoras de la integridad de las personas, de su dignidad y de sus derechos a todos aquellos que cumplen misiones en torno de presencia de las Naciones Unidas y del contingente.<\/i><\/p>\n<p><i>Sabemos que estas pr\u00e1cticas no vienen porque s\u00ed. Sabemos que hubo problemas en este sistema y algunos problemas graves. Como tuvimos circunstancias que censuramos o repudiamos a nivel de las acciones de distintos contingentes y a nivel del mundo, es que el Uruguay, que tiene una larga tradici\u00f3n de participaci\u00f3n en Misiones de Paz, se puso la tarea al hombro con las organizaciones del Reino Unido, con Naciones Unidas, con Unicef y con la Embajada para trabajar en la difusi\u00f3n de estas pr\u00e1cticas.<\/i><\/p>\n<p><b>Javier Garc\u00eda<br \/>\n<\/b>Ministro de Defensa Nacional<br \/>\nMinisterio de Defensa Nacional Uruguay<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Ministerio de Defensa Nacional de Uruguay ha lanzado una innovadora gu\u00eda de capacitaci\u00f3n sobre la protecci\u00f3n organizacional de la infancia contra la explotaci\u00f3n y el abuso en el contexto de las misiones de mantenimiento de la paz de las Naciones Unidas. La gu\u00eda, la primera a nivel mundial, fue desarrollada en colaboraci\u00f3n con Keeping [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":24611,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_eb_attr":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[90],"tags":[],"class_list":["post-13544","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Capacitaci\u00f3n del personal de mantenimiento de la paz de las Naciones Unidas en Protecci\u00f3n Infantil Organizacional - Keeping Children Safe<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.keepingchildrensafe.global\/es\/blog\/2021\/08\/17\/capacitacion-del-personal-de-mantenimiento-de-la-paz-de-las-naciones-unidas-en-proteccion-infantil-organizacional\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Capacitaci\u00f3n del personal de mantenimiento de la paz de las Naciones Unidas en Protecci\u00f3n Infantil Organizacional - Keeping Children Safe\" \/>\n<meta property=\"og:description\" content=\"El Ministerio de Defensa Nacional de Uruguay ha lanzado una innovadora gu\u00eda de capacitaci\u00f3n sobre la protecci\u00f3n organizacional de la infancia contra la explotaci\u00f3n y el abuso en el contexto de las misiones de mantenimiento de la paz de las Naciones Unidas. La gu\u00eda, la primera a nivel mundial, fue desarrollada en colaboraci\u00f3n con Keeping [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.keepingchildrensafe.global\/es\/blog\/2021\/08\/17\/capacitacion-del-personal-de-mantenimiento-de-la-paz-de-las-naciones-unidas-en-proteccion-infantil-organizacional\/\" \/>\n<meta property=\"og:site_name\" content=\"Keeping Children Safe\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/KCSkeepingchildrensafe\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-16T23:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-19T15:50:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.keepingchildrensafe.global\/wp-content\/uploads\/2023\/10\/16082021-DSC_0208.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1300\" \/>\n\t<meta property=\"og:image:height\" content=\"780\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Sarah Blakemore\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@keepchildsafe\" \/>\n<meta name=\"twitter:site\" content=\"@keepchildsafe\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sarah Blakemore\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.keepingchildrensafe.global\\\/es\\\/blog\\\/2021\\\/08\\\/17\\\/capacitacion-del-personal-de-mantenimiento-de-la-paz-de-las-naciones-unidas-en-proteccion-infantil-organizacional\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.keepingchildrensafe.global\\\/es\\\/blog\\\/2021\\\/08\\\/17\\\/capacitacion-del-personal-de-mantenimiento-de-la-paz-de-las-naciones-unidas-en-proteccion-infantil-organizacional\\\/\"},\"author\":{\"name\":\"Sarah Blakemore\",\"@id\":\"https:\\\/\\\/www.keepingchildrensafe.global\\\/es\\\/#\\\/schema\\\/person\\\/296ab02e4c5ce1e375fd5c8f487be2b0\"},\"headline\":\"Capacitaci\u00f3n del personal de mantenimiento de la paz de las Naciones Unidas en Protecci\u00f3n Infantil Organizacional\",\"datePublished\":\"2021-08-16T23:00:00+00:00\",\"dateModified\":\"2023-10-19T15:50:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.keepingchildrensafe.global\\\/es\\\/blog\\\/2021\\\/08\\\/17\\\/capacitacion-del-personal-de-mantenimiento-de-la-paz-de-las-naciones-unidas-en-proteccion-infantil-organizacional\\\/\"},\"wordCount\":665,\"publisher\":{\"@id\":\"https:\\\/\\\/www.keepingchildrensafe.global\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.keepingchildrensafe.global\\\/es\\\/blog\\\/2021\\\/08\\\/17\\\/capacitacion-del-personal-de-mantenimiento-de-la-paz-de-las-naciones-unidas-en-proteccion-infantil-organizacional\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.keepingchildrensafe.global\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/16082021-DSC_0208.jpg\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.keepingchildrensafe.global\\\/es\\\/blog\\\/2021\\\/08\\\/17\\\/capacitacion-del-personal-de-mantenimiento-de-la-paz-de-las-naciones-unidas-en-proteccion-infantil-organizacional\\\/\",\"url\":\"https:\\\/\\\/www.keepingchildrensafe.global\\\/es\\\/blog\\\/2021\\\/08\\\/17\\\/capacitacion-del-personal-de-mantenimiento-de-la-paz-de-las-naciones-unidas-en-proteccion-infantil-organizacional\\\/\",\"name\":\"Capacitaci\u00f3n del personal de mantenimiento de la paz de las Naciones Unidas en Protecci\u00f3n Infantil Organizacional - Keeping Children Safe\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.keepingchildrensafe.global\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.keepingchildrensafe.global\\\/es\\\/blog\\\/2021\\\/08\\\/17\\\/capacitacion-del-personal-de-mantenimiento-de-la-paz-de-las-naciones-unidas-en-proteccion-infantil-organizacional\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.keepingchildrensafe.global\\\/es\\\/blog\\\/2021\\\/08\\\/17\\\/capacitacion-del-personal-de-mantenimiento-de-la-paz-de-las-naciones-unidas-en-proteccion-infantil-organizacional\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.keepingchildrensafe.global\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/16082021-DSC_0208.jpg\",\"datePublished\":\"2021-08-16T23:00:00+00:00\",\"dateModified\":\"2023-10-19T15:50:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.keepingchildrensafe.global\\\/es\\\/blog\\\/2021\\\/08\\\/17\\\/capacitacion-del-personal-de-mantenimiento-de-la-paz-de-las-naciones-unidas-en-proteccion-infantil-organizacional\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.keepingchildrensafe.global\\\/es\\\/blog\\\/2021\\\/08\\\/17\\\/capacitacion-del-personal-de-mantenimiento-de-la-paz-de-las-naciones-unidas-en-proteccion-infantil-organizacional\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.keepingchildrensafe.global\\\/es\\\/blog\\\/2021\\\/08\\\/17\\\/capacitacion-del-personal-de-mantenimiento-de-la-paz-de-las-naciones-unidas-en-proteccion-infantil-organizacional\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.keepingchildrensafe.global\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/16082021-DSC_0208.jpg\",\"contentUrl\":\"https:\\\/\\\/www.keepingchildrensafe.global\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/16082021-DSC_0208.jpg\",\"width\":1300,\"height\":780},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.keepingchildrensafe.global\\\/es\\\/blog\\\/2021\\\/08\\\/17\\\/capacitacion-del-personal-de-mantenimiento-de-la-paz-de-las-naciones-unidas-en-proteccion-infantil-organizacional\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.keepingchildrensafe.global\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Capacitaci\u00f3n del personal de mantenimiento de la paz de las Naciones Unidas en Protecci\u00f3n Infantil Organizacional\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.keepingchildrensafe.global\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.keepingchildrensafe.global\\\/es\\\/\",\"name\":\"Keeping Children Safe\",\"description\":\"Setting tough International Child Safeguarding Standards\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.keepingchildrensafe.global\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.keepingchildrensafe.global\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.keepingchildrensafe.global\\\/es\\\/#organization\",\"name\":\"Keeping Children Safe\",\"url\":\"https:\\\/\\\/www.keepingchildrensafe.global\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.keepingchildrensafe.global\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/kcs.webscapegardener.site\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/kcs-header-logo.png\",\"contentUrl\":\"https:\\\/\\\/kcs.webscapegardener.site\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/kcs-header-logo.png\",\"width\":204,\"height\":21,\"caption\":\"Keeping Children Safe\"},\"image\":{\"@id\":\"https:\\\/\\\/www.keepingchildrensafe.global\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/KCSkeepingchildrensafe\",\"https:\\\/\\\/x.com\\\/keepchildsafe\",\"https:\\\/\\\/www.instagram.com\\\/keepingchildrensafe\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/keeping-children-safe-coalition\\\/\",\"https:\\\/\\\/vimeo.com\\\/keepingchildrensafe\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.keepingchildrensafe.global\\\/es\\\/#\\\/schema\\\/person\\\/296ab02e4c5ce1e375fd5c8f487be2b0\",\"name\":\"Sarah Blakemore\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a34551ffb55a79d2b33ef54566a9d965821e2eb7fc84cdd95151956aaf584a89?s=96&d=blank&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a34551ffb55a79d2b33ef54566a9d965821e2eb7fc84cdd95151956aaf584a89?s=96&d=blank&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a34551ffb55a79d2b33ef54566a9d965821e2eb7fc84cdd95151956aaf584a89?s=96&d=blank&r=g\",\"caption\":\"Sarah Blakemore\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Capacitaci\u00f3n del personal de mantenimiento de la paz de las Naciones Unidas en Protecci\u00f3n Infantil Organizacional - Keeping Children Safe","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.keepingchildrensafe.global\/es\/blog\/2021\/08\/17\/capacitacion-del-personal-de-mantenimiento-de-la-paz-de-las-naciones-unidas-en-proteccion-infantil-organizacional\/","og_locale":"es_ES","og_type":"article","og_title":"Capacitaci\u00f3n del personal de mantenimiento de la paz de las Naciones Unidas en Protecci\u00f3n Infantil Organizacional - Keeping Children Safe","og_description":"El Ministerio de Defensa Nacional de Uruguay ha lanzado una innovadora gu\u00eda de capacitaci\u00f3n sobre la protecci\u00f3n organizacional de la infancia contra la explotaci\u00f3n y el abuso en el contexto de las misiones de mantenimiento de la paz de las Naciones Unidas. La gu\u00eda, la primera a nivel mundial, fue desarrollada en colaboraci\u00f3n con Keeping [&hellip;]","og_url":"https:\/\/www.keepingchildrensafe.global\/es\/blog\/2021\/08\/17\/capacitacion-del-personal-de-mantenimiento-de-la-paz-de-las-naciones-unidas-en-proteccion-infantil-organizacional\/","og_site_name":"Keeping Children Safe","article_publisher":"https:\/\/www.facebook.com\/KCSkeepingchildrensafe","article_published_time":"2021-08-16T23:00:00+00:00","article_modified_time":"2023-10-19T15:50:48+00:00","og_image":[{"width":1300,"height":780,"url":"https:\/\/www.keepingchildrensafe.global\/wp-content\/uploads\/2023\/10\/16082021-DSC_0208.jpg","type":"image\/jpeg"}],"author":"Sarah Blakemore","twitter_card":"summary_large_image","twitter_creator":"@keepchildsafe","twitter_site":"@keepchildsafe","twitter_misc":{"Escrito por":"Sarah Blakemore","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.keepingchildrensafe.global\/es\/blog\/2021\/08\/17\/capacitacion-del-personal-de-mantenimiento-de-la-paz-de-las-naciones-unidas-en-proteccion-infantil-organizacional\/#article","isPartOf":{"@id":"https:\/\/www.keepingchildrensafe.global\/es\/blog\/2021\/08\/17\/capacitacion-del-personal-de-mantenimiento-de-la-paz-de-las-naciones-unidas-en-proteccion-infantil-organizacional\/"},"author":{"name":"Sarah Blakemore","@id":"https:\/\/www.keepingchildrensafe.global\/es\/#\/schema\/person\/296ab02e4c5ce1e375fd5c8f487be2b0"},"headline":"Capacitaci\u00f3n del personal de mantenimiento de la paz de las Naciones Unidas en Protecci\u00f3n Infantil Organizacional","datePublished":"2021-08-16T23:00:00+00:00","dateModified":"2023-10-19T15:50:48+00:00","mainEntityOfPage":{"@id":"https:\/\/www.keepingchildrensafe.global\/es\/blog\/2021\/08\/17\/capacitacion-del-personal-de-mantenimiento-de-la-paz-de-las-naciones-unidas-en-proteccion-infantil-organizacional\/"},"wordCount":665,"publisher":{"@id":"https:\/\/www.keepingchildrensafe.global\/es\/#organization"},"image":{"@id":"https:\/\/www.keepingchildrensafe.global\/es\/blog\/2021\/08\/17\/capacitacion-del-personal-de-mantenimiento-de-la-paz-de-las-naciones-unidas-en-proteccion-infantil-organizacional\/#primaryimage"},"thumbnailUrl":"https:\/\/www.keepingchildrensafe.global\/wp-content\/uploads\/2023\/10\/16082021-DSC_0208.jpg","articleSection":["Noticias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.keepingchildrensafe.global\/es\/blog\/2021\/08\/17\/capacitacion-del-personal-de-mantenimiento-de-la-paz-de-las-naciones-unidas-en-proteccion-infantil-organizacional\/","url":"https:\/\/www.keepingchildrensafe.global\/es\/blog\/2021\/08\/17\/capacitacion-del-personal-de-mantenimiento-de-la-paz-de-las-naciones-unidas-en-proteccion-infantil-organizacional\/","name":"Capacitaci\u00f3n del personal de mantenimiento de la paz de las Naciones Unidas en Protecci\u00f3n Infantil Organizacional - Keeping Children Safe","isPartOf":{"@id":"https:\/\/www.keepingchildrensafe.global\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.keepingchildrensafe.global\/es\/blog\/2021\/08\/17\/capacitacion-del-personal-de-mantenimiento-de-la-paz-de-las-naciones-unidas-en-proteccion-infantil-organizacional\/#primaryimage"},"image":{"@id":"https:\/\/www.keepingchildrensafe.global\/es\/blog\/2021\/08\/17\/capacitacion-del-personal-de-mantenimiento-de-la-paz-de-las-naciones-unidas-en-proteccion-infantil-organizacional\/#primaryimage"},"thumbnailUrl":"https:\/\/www.keepingchildrensafe.global\/wp-content\/uploads\/2023\/10\/16082021-DSC_0208.jpg","datePublished":"2021-08-16T23:00:00+00:00","dateModified":"2023-10-19T15:50:48+00:00","breadcrumb":{"@id":"https:\/\/www.keepingchildrensafe.global\/es\/blog\/2021\/08\/17\/capacitacion-del-personal-de-mantenimiento-de-la-paz-de-las-naciones-unidas-en-proteccion-infantil-organizacional\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.keepingchildrensafe.global\/es\/blog\/2021\/08\/17\/capacitacion-del-personal-de-mantenimiento-de-la-paz-de-las-naciones-unidas-en-proteccion-infantil-organizacional\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.keepingchildrensafe.global\/es\/blog\/2021\/08\/17\/capacitacion-del-personal-de-mantenimiento-de-la-paz-de-las-naciones-unidas-en-proteccion-infantil-organizacional\/#primaryimage","url":"https:\/\/www.keepingchildrensafe.global\/wp-content\/uploads\/2023\/10\/16082021-DSC_0208.jpg","contentUrl":"https:\/\/www.keepingchildrensafe.global\/wp-content\/uploads\/2023\/10\/16082021-DSC_0208.jpg","width":1300,"height":780},{"@type":"BreadcrumbList","@id":"https:\/\/www.keepingchildrensafe.global\/es\/blog\/2021\/08\/17\/capacitacion-del-personal-de-mantenimiento-de-la-paz-de-las-naciones-unidas-en-proteccion-infantil-organizacional\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.keepingchildrensafe.global\/es\/"},{"@type":"ListItem","position":2,"name":"Capacitaci\u00f3n del personal de mantenimiento de la paz de las Naciones Unidas en Protecci\u00f3n Infantil Organizacional"}]},{"@type":"WebSite","@id":"https:\/\/www.keepingchildrensafe.global\/es\/#website","url":"https:\/\/www.keepingchildrensafe.global\/es\/","name":"Keeping Children Safe","description":"Setting tough International Child Safeguarding Standards","publisher":{"@id":"https:\/\/www.keepingchildrensafe.global\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.keepingchildrensafe.global\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.keepingchildrensafe.global\/es\/#organization","name":"Keeping Children Safe","url":"https:\/\/www.keepingchildrensafe.global\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.keepingchildrensafe.global\/es\/#\/schema\/logo\/image\/","url":"https:\/\/kcs.webscapegardener.site\/wp-content\/uploads\/2023\/10\/kcs-header-logo.png","contentUrl":"https:\/\/kcs.webscapegardener.site\/wp-content\/uploads\/2023\/10\/kcs-header-logo.png","width":204,"height":21,"caption":"Keeping Children Safe"},"image":{"@id":"https:\/\/www.keepingchildrensafe.global\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/KCSkeepingchildrensafe","https:\/\/x.com\/keepchildsafe","https:\/\/www.instagram.com\/keepingchildrensafe\/","https:\/\/www.linkedin.com\/company\/keeping-children-safe-coalition\/","https:\/\/vimeo.com\/keepingchildrensafe"]},{"@type":"Person","@id":"https:\/\/www.keepingchildrensafe.global\/es\/#\/schema\/person\/296ab02e4c5ce1e375fd5c8f487be2b0","name":"Sarah Blakemore","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/a34551ffb55a79d2b33ef54566a9d965821e2eb7fc84cdd95151956aaf584a89?s=96&d=blank&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a34551ffb55a79d2b33ef54566a9d965821e2eb7fc84cdd95151956aaf584a89?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a34551ffb55a79d2b33ef54566a9d965821e2eb7fc84cdd95151956aaf584a89?s=96&d=blank&r=g","caption":"Sarah Blakemore"}}]}},"_links":{"self":[{"href":"https:\/\/www.keepingchildrensafe.global\/es\/wp-json\/wp\/v2\/posts\/13544","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.keepingchildrensafe.global\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.keepingchildrensafe.global\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.keepingchildrensafe.global\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.keepingchildrensafe.global\/es\/wp-json\/wp\/v2\/comments?post=13544"}],"version-history":[{"count":1,"href":"https:\/\/www.keepingchildrensafe.global\/es\/wp-json\/wp\/v2\/posts\/13544\/revisions"}],"predecessor-version":[{"id":24942,"href":"https:\/\/www.keepingchildrensafe.global\/es\/wp-json\/wp\/v2\/posts\/13544\/revisions\/24942"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.keepingchildrensafe.global\/es\/wp-json\/wp\/v2\/media\/24611"}],"wp:attachment":[{"href":"https:\/\/www.keepingchildrensafe.global\/es\/wp-json\/wp\/v2\/media?parent=13544"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.keepingchildrensafe.global\/es\/wp-json\/wp\/v2\/categories?post=13544"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.keepingchildrensafe.global\/es\/wp-json\/wp\/v2\/tags?post=13544"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}